
{"id":1592,"count":1,"description":"","link":"https:\/\/www.essentialhome.eu\/blog\/tag\/easter-basket\/","name":"easter basket","slug":"easter-basket","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/tags\/1592"}],"collection":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/posts?tags=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}