{"id":1001,"count":1,"description":"","link":"https:\/\/www.essentialhome.eu\/blog\/tag\/color-blocking-trend\/","name":"Color Blocking Trend","slug":"color-blocking-trend","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/tags\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.essentialhome.eu\/blog\/wp-json\/wp\/v2\/posts?tags=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}